{"id":2168,"date":"2022-03-03T11:37:41","date_gmt":"2022-03-03T11:37:41","guid":{"rendered":"https:\/\/galeriametges.comib.com\/?p=2168"},"modified":"2022-12-14T13:19:11","modified_gmt":"2022-12-14T13:19:11","slug":"institucions-ejemplo-no2","status":"publish","type":"post","link":"https:\/\/galeriametges.comib.com\/es\/institucions-ejemplo-no2\/","title":{"rendered":"Hospital Sant Joan de D\u00e9u Palma"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-top vc_row-flex\"><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: left\" class=\"vc_custom_heading\" >Hospital Sant Joan de D\u00e9u Palma<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2314\" src=\"https:\/\/galeriametges.comib.com\/wp-content\/uploads\/2022\/03\/El-Sanatorio-infantil-de-San-Juan-de-Dios-en-construccion.-Anos-1953-o-1954.bmp\" alt=\"\" width=\"421\" height=\"288\" \/><\/p>\n<div id=\"bannerR\">\n<div id=\"div-gpt-ad-1474537762122-3\" data-google-query-id=\"CMOdwNHNqfYCFfhapAQd6IkN2Q\">\n<div id=\"google_ads_iframe_\/15188745,22440292294\/Lipsum-Unit4_0__container__\">\n<p><strong>Resumen de la historia del Hospital San Juan de Dios de Palma de Mallorca (HSJD)<\/strong><\/p>\n<p>En el verano de 2020, un joven aislado por COVID-19 en el hospital San Juan de Dios de Palma de Mallorca no sospecha, que all\u00ed, cerca del mar, hace 65 a\u00f1os se ubicaba un sanatorio infantil, creado por la Orden Hospitalaria de San Juan de Dios, una instituci\u00f3n ben\u00e9fica fundada en el siglo XVI en Granada (Espa\u00f1a) por Juan Ciudad, m\u00e1s tarde San Juan de Dios, con el objetivo de ofrecer asistencia sanitaria a la poblaci\u00f3n m\u00e1s necesitada. Sus abuelos, sin embargo, s\u00ed recordar\u00edan a los Hermanos de la Orden pidiendo limosna en la ciudad de Palma para poder sustentar la atenci\u00f3n sanitaria y escolarizaci\u00f3n de aquellos ni\u00f1os discapacitados y desfavorecidos en la Mallorca de la postguerra civil. Transformado en hospital en los a\u00f1os 70 y hasta la actualidad, ha ido adapt\u00e1ndose a las demandas sociales de su entorno, siendo adem\u00e1s innovador en muchos aspectos m\u00e9dicos.<\/p>\n<p>Los or\u00edgenes de sanatorio SJD de Palma se remontan a la primera d\u00e9cada del siglo XX, fruto una de la donaci\u00f3n filantr\u00f3pica de los esposos Ramon Vallespir Garcias y Antonia Ferr\u00e0 Aloy, constituida ante Notario el 20 de septiembre de 1909. \u00a0La donaci\u00f3n estaba destinada a la construcci\u00f3n y habilitaci\u00f3n de un hospital para ni\u00f1os enfermos pobres y que se har\u00eda efectiva a la muerte de ambos c\u00f3nyuges, que no ocurri\u00f3 hasta 1917. Despu\u00e9s de resolver toda una serie de cuestiones relacionadas con la donaci\u00f3n y evaluar las diferentes localizaciones, en noviembre de 1927 los albaceas compraron un solar ubicado a cinco kil\u00f3metros de la capital, en una zona conocida como el Coll d\u2019en Rabassa en la costa suroeste de la bah\u00eda de Palma, cerca de donde hoy est\u00e1 ubicado el aeropuerto Son Sant Joan de Palma de Mallorca. Esta ubicaci\u00f3n no fue casual, si no que respond\u00eda a la necesidad de ubicar el sanatorio cerca de la costa, en contacto con la naturaleza y alejada de la urbe, acorde a las corrientes higienistas de la \u00e9poca que retomaban el uso de los agentes naturales ya presentes en la medicina antigua y resurgida a partir del siglo XIX.<\/p>\n<p>Para el dise\u00f1o del edificio se contact\u00f3 con el afamado arquitecto catal\u00e1n Don Sixto Illescas i Mirosa y su colega mallorqu\u00edn Don Jos\u00e9 Alomar Bosch. El edificio ten\u00eda una disposici\u00f3n claramente sanatorial con una capacidad entre 40 y 50 camas infantiles. La orientaci\u00f3n asistencial se establec\u00eda enfocada a la poblaci\u00f3n vulnerable infantil afecta de procesos invalidantes de poliomielitis, par\u00e1lisis cerebral infantil, tuberculosis \u00f3sea, mielomeningocele, etc., con gratuidad total para los ingresados. La inauguraci\u00f3n tuvo lugar el 4 de diciembre de 1955. A partir de esta fecha se inici\u00f3 la actividad hospitalaria sustentada por un equipo de m\u00e9dicos especialistas apoyados por los Hermanos Hospitalarios que adem\u00e1s de proveer las necesidades del hospital, colaboraban con su labor enfermera, participando en la actividad quir\u00fargica, en la rehabilitaci\u00f3n y en los cuidados generales. En 1963 cuando se iniciaron las vacunaciones anti polio se aplic\u00f3 la vacuna Salk en varias etapas de inmunizaci\u00f3n<\/p>\n<p>Se dispuso tambi\u00e9n una Escuela Hospitalaria para los ni\u00f1os ingresados, proporcionando as\u00ed una Primera Ense\u00f1anza equiparable a las escuelas oficiales. Tambi\u00e9n se planificaron y pusieron en marcha las Escuelas Profesionales de Ayudantes T\u00e9cnicos Sanitario (ATS) y de Fisioterapia para ir formando profesionales sanitarios<\/p>\n<p>A partir del a\u00f1o 1968, toda vez que la poliomielitis iba decreciendo, se dispuso del primer Concierto con la Seguridad Social y con ello se dio pie a admitir adem\u00e1s a pacientes adultos afectos de procesos invalidantes, potenciando la Cirug\u00eda Ortop\u00e9dica y la Rehabilitaci\u00f3n del adulto<\/p>\n<p>A partir del a\u00f1o 1975 tuvo lugar la primera gran transformaci\u00f3n del hospital, el cual paso a ser un hospital de Adultos orientado a la Cirug\u00eda Ortop\u00e9dica, la Traumatolog\u00eda y la Rehabilitaci\u00f3n con una capacidad de 75 camas. Destaca la amplia experiencia en implantologia articular<\/p>\n<p>A partir de 1998 el Hospital inicia la atenci\u00f3n geri\u00e1trica integral implant\u00e1ndose el primer Hospital de D\u00eda geri\u00e1trico con 15 plazas, la creaci\u00f3n de la Unidad Geri\u00e1trica de Agudos, de Media Estancia, la Unidad de Ortogeriatria y la Unidad geri\u00e1trica de Larga Estancia. En dicha fase hay que se\u00f1alar que tambi\u00e9n se pone en marcha la primera Unidad de Cirug\u00eda mayor\/ menor ambulatoria de Cirug\u00eda Ortop\u00e9dica de nuestra Comunidad Aut\u00f3noma. En 2005 se coloca la primera piedra del nuevo edificio hospitalario y se inicia la nueva construcci\u00f3n que dar\u00e1 un nuevo aspecto a la cl\u00e1sica imagen sanatorial que todav\u00eda presentaba el hospital.<\/p>\n<p>A partir de 2007 se trabaja intensamente con el objeto de lograr una plena integraci\u00f3n del Hospital de San Juan de Dios en la Red P\u00fablica de Asistencia Sanitaria, lo cual se consigue a partir de 2013. A la vez se inaugura el nuevo pabell\u00f3n hospitalario que dar\u00e1 cabida a consultas externas, servicios de Rx, gimnasio y hospitalizaci\u00f3n. Las camas pasan a 110, y se inicia la remodelaci\u00f3n del edificio antiguo que al finalizar en 2014 llega a ofertar 150 camas hospitalarias. A la vez la orientaci\u00f3n sanitaria se enfoca hacia favorecer en conjunto la autonom\u00eda de las personas, potenciando la neurorrehabilitacion, el da\u00f1o neurol\u00f3gico central y medular, las curas paliativas, sin prescindir de los cl\u00e1sicos servicios de Cirug\u00eda Ortop\u00e9dica, Traumatolog\u00eda y Rehabilitaci\u00f3n motora. En 2015 la Orden Hospitalaria de San Juan de Dios recibe el premio Princesa de Asturias de la Concordia. Con ocasi\u00f3n de la pandemia por Covid-19 el Hospital de San Juan de Dios, dentro de la Red de Hospitales P\u00fablicos, ha supuesto una colaboraci\u00f3n imprescindible en el tratamiento de estos pacientes.<\/p>\n<p>&nbsp;<\/p>\n<p>Joaqu\u00edn Boronat Rom<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat. Ut wisi enim ad minim veniam, quis nostrud exerci tation ullamcorper suscipit lobortis.<\/p>","protected":false},"author":1,"featured_media":2314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[424],"tags":[],"class_list":["post-2168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucions"],"_links":{"self":[{"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/posts\/2168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/comments?post=2168"}],"version-history":[{"count":9,"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/posts\/2168\/revisions"}],"predecessor-version":[{"id":2315,"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/posts\/2168\/revisions\/2315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/media\/2314"}],"wp:attachment":[{"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/media?parent=2168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/categories?post=2168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/galeriametges.comib.com\/es\/wp-json\/wp\/v2\/tags?post=2168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}